{"id":968,"date":"2022-03-03T22:54:10","date_gmt":"2022-03-03T14:54:10","guid":{"rendered":"http:\/\/nekosuites.com\/hotel-kucing-neko-suites-penginapan-kucing-di-ipoh\/"},"modified":"2024-03-20T13:32:05","modified_gmt":"2024-03-20T13:32:05","slug":"hotel-kucing-neko-suites","status":"publish","type":"page","link":"https:\/\/nekosuites.com\/ms\/","title":{"rendered":"Hotel Kucing Neko Suites &#8211; Penginapan Kucing Di Ipoh"},"content":{"rendered":"<style>.kb-row-layout-id968_74f4f0-fe > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id968_74f4f0-fe > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id968_74f4f0-fe > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:60px;min-height:950px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id968_74f4f0-fe > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id968_74f4f0-fe > .kt-row-column-wrap{min-height:600px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id968_74f4f0-fe > .kt-row-column-wrap{min-height:500px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id968_74f4f0-fe alignnone has-theme-palette7-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column968_be54cf-fd > .kt-inside-inner-col{display:flex;}.kadence-column968_be54cf-fd > .kt-inside-inner-col,.kadence-column968_be54cf-fd > .kt-inside-inner-col:before{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kadence-column968_be54cf-fd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_be54cf-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_be54cf-fd > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column968_be54cf-fd{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_be54cf-fd{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_be54cf-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_be54cf-fd > .kt-inside-inner-col{background-image:url('http:\/\/nekosuites.com\/wp-content\/uploads\/Orange-close-up-1.jpg');background-size:cover;background-position:60% 53%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column968_be54cf-fd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_be54cf-fd{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column968_be54cf-fd{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_be54cf-fd{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_be54cf-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column968_be54cf-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column968_be54cf-fd{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_be54cf-fd{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_be54cf-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_be54cf-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column968_be54cf-fd { }<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_be54cf-fd inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-968_3c1611-35 .kt-block-spacer{height:350px;}.wp-block-kadence-spacer.kt-block-spacer-968_3c1611-35 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-968_3c1611-35 kvs-lg-false kvs-md-false\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column968_2895f8-f0 > .kt-inside-inner-col{display:flex;}.kadence-column968_2895f8-f0 > .kt-inside-inner-col,.kadence-column968_2895f8-f0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_2895f8-f0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_2895f8-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_2895f8-f0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column968_2895f8-f0{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_2895f8-f0{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_2895f8-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_2895f8-f0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_2895f8-f0{text-align:left;}.kadence-column968_2895f8-f0{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column968_2895f8-f0{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_2895f8-f0{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_2895f8-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column968_2895f8-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column968_2895f8-f0{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_2895f8-f0{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_2895f8-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_2895f8-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_2895f8-f0 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id968_f57f51-bc > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id968_f57f51-bc > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id968_f57f51-bc > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:500px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id968_f57f51-bc > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id968_f57f51-bc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id968_f57f51-bc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id968_f57f51-bc alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column968_c9817a-b5 > .kt-inside-inner-col,.kadence-column968_c9817a-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_c9817a-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_c9817a-b5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_c9817a-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_c9817a-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_c9817a-b5{position:relative;}@media all and (max-width: 1024px){.kadence-column968_c9817a-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_c9817a-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column968_c9817a-b5 { }<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_c9817a-b5 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading968_bf6a8a-8e, .wp-block-kadence-advancedheading.kt-adv-heading968_bf6a8a-8e[data-kb-block=\"kb-adv-heading968_bf6a8a-8e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading968_bf6a8a-8e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_bf6a8a-8e[data-kb-block=\"kb-adv-heading968_bf6a8a-8e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_bf6a8a-8e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_bf6a8a-8e[data-kb-block=\"kb-adv-heading968_bf6a8a-8e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading968_bf6a8a-8e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading968_bf6a8a-8e\">Hotel Kucing Neko Suites &#8211; Penginapan Kucing Di Ipoh<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading968_49bfb1-e7, .wp-block-kadence-advancedheading.kt-adv-heading968_49bfb1-e7[data-kb-block=\"kb-adv-heading968_49bfb1-e7\"]{font-size:20px;line-height:23.46px;font-weight:400;font-style:normal;font-family:'Work Sans';}.wp-block-kadence-advancedheading.kt-adv-heading968_49bfb1-e7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_49bfb1-e7[data-kb-block=\"kb-adv-heading968_49bfb1-e7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_49bfb1-e7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_49bfb1-e7[data-kb-block=\"kb-adv-heading968_49bfb1-e7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading968_49bfb1-e7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading968_49bfb1-e7\">Tempah penginapan percutian buat kucing anda.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c, .wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c[data-kb-block=\"kb-adv-heading968_8f70b0-8c\"]{font-size:38px;line-height:56px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c[data-kb-block=\"kb-adv-heading968_8f70b0-8c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c[data-kb-block=\"kb-adv-heading968_8f70b0-8c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c, .wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c[data-kb-block=\"kb-adv-heading968_8f70b0-8c\"]{font-size:38px;line-height:56px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c, .wp-block-kadence-advancedheading.kt-adv-heading968_8f70b0-8c[data-kb-block=\"kb-adv-heading968_8f70b0-8c\"]{font-size:36px;line-height:50px;}}<\/style>\n<h2 class=\"kt-adv-heading968_8f70b0-8c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading968_8f70b0-8c\">Kami ingin membuatkan kucing anda berasa seperti di rumah sendiri di hotel kucing kami di Ipoh.<\/h2>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns968_abf5eb-36{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns968_abf5eb-36 .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns968_abf5eb-36{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns968_abf5eb-36\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);padding-right:55px;padding-left:55px;}.wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button:focus{color:var(--global-palette2, #2B6CB0);background:var(--global-palette1, #3182CE);border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button{border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button{border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);}.wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_130b59-ef.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn968_130b59-ef kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/nekosuites.com\/ms\/penginapan\/\"><span class=\"kt-btn-inner-text\">Lihat Penginapan Kami<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button{color:var(--global-palette9, #ffffff);background:#25d366;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:1px solid #25d366;border-right:1px solid #25d366;border-bottom:1px solid #25d366;border-left:1px solid #25d366;padding-right:55px;padding-left:55px;}.wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button:focus{color:var(--global-palette2, #2B6CB0);background:var(--global-palette1, #3182CE);border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button{border-top:1px solid #25d366;border-right:1px solid #25d366;border-bottom:1px solid #25d366;border-left:1px solid #25d366;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button{border-top:1px solid #25d366;border-right:1px solid #25d366;border-bottom:1px solid #25d366;border-left:1px solid #25d366;}.wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_798ff7-ea.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn968_798ff7-ea kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/api.whatsapp.com\/send?phone=60175863165\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">WhatsApp Kami<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id968_2dafb6-cb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id968_2dafb6-cb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id968_2dafb6-cb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:40px;padding-bottom:40px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id968_2dafb6-cb > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){.kb-row-layout-id968_2dafb6-cb{display:none !important;}}@media all and (max-width: 1024px){.kb-row-layout-id968_2dafb6-cb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id968_2dafb6-cb{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-id968_2dafb6-cb > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id968_2dafb6-cb{display:none !important;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id968_2dafb6-cb alignnone kb-v-lg-hidden kb-v-md-hidden kb-v-sm-hidden wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column968_af9e7d-00 > .kt-inside-inner-col,.kadence-column968_af9e7d-00 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_af9e7d-00 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_af9e7d-00 > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_af9e7d-00 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_af9e7d-00 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_af9e7d-00{position:relative;}@media all and (max-width: 1024px){.kadence-column968_af9e7d-00 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_af9e7d-00 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_af9e7d-00 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading968_f9bd11-93, .wp-block-kadence-advancedheading.kt-adv-heading968_f9bd11-93[data-kb-block=\"kb-adv-heading968_f9bd11-93\"]{text-align:center;font-size:56px;line-height:70px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading968_f9bd11-93 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_f9bd11-93[data-kb-block=\"kb-adv-heading968_f9bd11-93\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_f9bd11-93 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_f9bd11-93[data-kb-block=\"kb-adv-heading968_f9bd11-93\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading968_f9bd11-93, .wp-block-kadence-advancedheading.kt-adv-heading968_f9bd11-93[data-kb-block=\"kb-adv-heading968_f9bd11-93\"]{font-size:36px;}}<\/style>\n<h2 class=\"kt-adv-heading968_f9bd11-93 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading968_f9bd11-93\">Kemudahan Di Hotel Kucing Neko Suites, Ipoh<\/h2>\n\n\n<style>.kb-row-layout-id968_645418-2e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id968_645418-2e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id968_645418-2e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1475px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:25px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kb-row-layout-id968_645418-2e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id968_645418-2e > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id968_645418-2e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id968_645418-2e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id968_645418-2e > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id968_645418-2e > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id968_645418-2e > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id968_645418-2e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-two-grid kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column968_8ce64d-90 > .kt-inside-inner-col,.kadence-column968_8ce64d-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_8ce64d-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_8ce64d-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_8ce64d-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_8ce64d-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_8ce64d-90{position:relative;}@media all and (max-width: 1024px){.kadence-column968_8ce64d-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_8ce64d-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_8ce64d-90 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image968_d7e3e3-b0 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_d7e3e3-b0 img.kb-img, .kb-image968_d7e3e3-b0 .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_d7e3e3-b0\"><img alt=\"\" class=\"kb-img\" title=\"\"\/><figcaption>Penyaman Udara<\/figcaption><\/figure>\n\n\n<style>.kb-image968_a7df29-05 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_a7df29-05 img.kb-img, .kb-image968_a7df29-05 .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_a7df29-05\"><img alt=\"\" class=\"kb-img\" title=\"\"\/><figcaption>Pintu Berganda<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column968_53d9f5-b0 > .kt-inside-inner-col,.kadence-column968_53d9f5-b0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_53d9f5-b0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_53d9f5-b0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_53d9f5-b0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_53d9f5-b0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_53d9f5-b0{position:relative;}@media all and (max-width: 1024px){.kadence-column968_53d9f5-b0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_53d9f5-b0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_53d9f5-b0 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image968_dbaeb7-ca .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_dbaeb7-ca img.kb-img, .kb-image968_dbaeb7-ca .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_dbaeb7-ca\"><img alt=\"\" class=\"kb-img\" title=\"\"\/><figcaption>Makanan Berkualiti<\/figcaption><\/figure>\n\n\n<style>.kb-image968_129bb0-80 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_129bb0-80 img.kb-img, .kb-image968_129bb0-80 .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_129bb0-80\"><img alt=\"\" class=\"kb-img\" title=\"\"\/><figcaption>Persekitaran Bebas Anjing<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column968_4c75d9-51 > .kt-inside-inner-col,.kadence-column968_4c75d9-51 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_4c75d9-51 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_4c75d9-51 > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_4c75d9-51 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_4c75d9-51 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_4c75d9-51{position:relative;}@media all and (max-width: 1024px){.kadence-column968_4c75d9-51 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_4c75d9-51 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_4c75d9-51 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kb-image968_a0f14e-88 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_a0f14e-88 img.kb-img, .kb-image968_a0f14e-88 .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_a0f14e-88\"><img alt=\"\" class=\"kb-img\" title=\"\"\/><figcaption>Air Minuman Yang Ditapis<\/figcaption><\/figure>\n\n\n<style>.kb-image968_fc88c4-5e .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_fc88c4-5e img.kb-img, .kb-image968_fc88c4-5e .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_fc88c4-5e\"><img alt=\"\" class=\"kb-img\" title=\"\"\/><figcaption>Masa bermain<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column968_4b6ecf-52 > .kt-inside-inner-col,.kadence-column968_4b6ecf-52 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_4b6ecf-52 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_4b6ecf-52 > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_4b6ecf-52 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_4b6ecf-52 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_4b6ecf-52{position:relative;}@media all and (max-width: 1024px){.kadence-column968_4b6ecf-52 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_4b6ecf-52 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_4b6ecf-52 inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kb-image968_29bcd7-1c .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_29bcd7-1c img.kb-img, .kb-image968_29bcd7-1c .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_29bcd7-1c\"><img alt=\"\" class=\"kb-img\" title=\"\"\/><figcaption>Cat Cam<\/figcaption><\/figure>\n\n\n<style>.kb-image968_5352db-ee .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_5352db-ee img.kb-img, .kb-image968_5352db-ee .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_5352db-ee\"><img alt=\"\" class=\"kb-img\" title=\"\"\/><figcaption>Persekitaran Bersih<\/figcaption><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-image968_8277be-aa.kb-image-is-ratio-size, .kb-image968_8277be-aa .kb-image-is-ratio-size{max-width:800px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image968_8277be-aa.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image968_8277be-aa .kb-image-is-ratio-size{align-self:unset;}.kb-image968_8277be-aa figure{max-width:800px;}.kb-image968_8277be-aa .image-is-svg, .kb-image968_8277be-aa .image-is-svg img{width:100%;}.kb-image968_8277be-aa .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;}.kb-image968_8277be-aa img.kb-img, .kb-image968_8277be-aa .kb-img img{border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image968_8277be-aa:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:25px;margin-left:25px;}}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image968_8277be-aa:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:25px;margin-left:25px;}}<\/style>\n<div class=\"wp-block-kadence-image kb-image968_8277be-aa\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/nekosuites.com\/wp-content\/uploads\/\/Playroom-At-Neko-Suites-Cat-Hotel-In-Ipoh-1024x768.jpg\" alt=\"Bilik Permainan Di Hotel Kucing Neko Suites, Ipoh\" class=\"kb-img wp-image-1265\" srcset=\"https:\/\/nekosuites.com\/wp-content\/uploads\/Playroom-At-Neko-Suites-Cat-Hotel-In-Ipoh-1024x768.jpg 1024w, https:\/\/nekosuites.com\/wp-content\/uploads\/Playroom-At-Neko-Suites-Cat-Hotel-In-Ipoh-300x225.jpg 300w, https:\/\/nekosuites.com\/wp-content\/uploads\/Playroom-At-Neko-Suites-Cat-Hotel-In-Ipoh-768x576.jpg 768w, https:\/\/nekosuites.com\/wp-content\/uploads\/Playroom-At-Neko-Suites-Cat-Hotel-In-Ipoh.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.kb-row-layout-id968_5d5fe3-b3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id968_5d5fe3-b3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id968_5d5fe3-b3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:900px;margin-left:auto;margin-right:auto;padding-top:41px;padding-right:25px;padding-bottom:40px;padding-left:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id968_5d5fe3-b3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id968_5d5fe3-b3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id968_5d5fe3-b3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id968_5d5fe3-b3 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column968_28d05d-1f > .kt-inside-inner-col,.kadence-column968_28d05d-1f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_28d05d-1f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_28d05d-1f > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_28d05d-1f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_28d05d-1f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_28d05d-1f{text-align:center;}.kadence-column968_28d05d-1f{position:relative;}@media all and (max-width: 1024px){.kadence-column968_28d05d-1f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_28d05d-1f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column968_28d05d-1f { }<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_28d05d-1f inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading968_35bdc4-90, .wp-block-kadence-advancedheading.kt-adv-heading968_35bdc4-90[data-kb-block=\"kb-adv-heading968_35bdc4-90\"]{text-align:center;font-size:20px;font-weight:400;font-style:normal;font-family:'Work Sans';}.wp-block-kadence-advancedheading.kt-adv-heading968_35bdc4-90 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_35bdc4-90[data-kb-block=\"kb-adv-heading968_35bdc4-90\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_35bdc4-90 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_35bdc4-90[data-kb-block=\"kb-adv-heading968_35bdc4-90\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading968_35bdc4-90 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading968_35bdc4-90\">Misi Kami<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading968_677070-04, .wp-block-kadence-advancedheading.kt-adv-heading968_677070-04[data-kb-block=\"kb-adv-heading968_677070-04\"]{font-size:36px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading968_677070-04 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_677070-04[data-kb-block=\"kb-adv-heading968_677070-04\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_677070-04 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_677070-04[data-kb-block=\"kb-adv-heading968_677070-04\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading968_677070-04 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading968_677070-04\">Ingin pergi ke mana-mana tetapi tidak boleh bawa kucing kesayangan? Kami faham perasaan anda. <\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns968_4af7fe-3f{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns968_4af7fe-3f .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns968_4af7fe-3f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);font-size:nonepx;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);padding-right:55px;padding-left:55px;}.wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button:focus{color:var(--global-palette2, #2B6CB0);background:var(--global-palette1, #3182CE);border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button{border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button{border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);}.wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_0f955b-1a.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn968_0f955b-1a kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/nekosuites.com\/ms\/tentang-kami\/\"><span class=\"kt-btn-inner-text\">Tentang Kami<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1475px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-right:25px;padding-bottom:65px;padding-left:25px;min-height:572px;}.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr) minmax(0, 1fr);}.kb-row-layout-id968_7aeb87-bb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap > *:nth-child(3n+1 of *:not(style)){grid-column:1 \/ -1;}}@media all and (max-width: 1024px){.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap > *:nth-child(3n+1 of *:not(style)){grid-column:1 \/ -1;}.kb-row-layout-id968_7aeb87-bb > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id968_7aeb87-bb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-left-half kt-tab-layout-first-row kt-mobile-layout-first-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column968_84df07-f1 > .kt-inside-inner-col{display:flex;}.kadence-column968_84df07-f1 > .kt-inside-inner-col{padding-right:60px;padding-left:60px;}.kadence-column968_84df07-f1 > .kt-inside-inner-col,.kadence-column968_84df07-f1 > .kt-inside-inner-col:before{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kadence-column968_84df07-f1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_84df07-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_84df07-f1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column968_84df07-f1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_84df07-f1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_84df07-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_84df07-f1 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column968_84df07-f1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_84df07-f1{text-align:center;}.kadence-column968_84df07-f1{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column968_84df07-f1{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_84df07-f1{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_84df07-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column968_84df07-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_84df07-f1 > .kt-inside-inner-col{padding-top:20px;padding-right:25px;padding-bottom:20px;padding-left:25px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column968_84df07-f1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_84df07-f1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_84df07-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_84df07-f1, .kt-inside-inner-col > .kadence-column968_84df07-f1:not(.specificity){margin-bottom:25px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_84df07-f1 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26, .wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"]{text-align:center;font-size:56px;line-height:70px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"] mark.kt-highlight{font-style:normal;color:#f76a0c;border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"] a, .kt-adv-heading-link968_0a820c-26, .kt-adv-heading-link968_0a820c-26 .kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"]{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"] a, a.kb-advanced-heading-link.kt-adv-heading-link968_0a820c-26{text-decoration:none;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26, .wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"]{padding-right:20px;padding-left:20px;font-size:42px;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"] mark.kt-highlight{border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26, .wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"]{padding-top:20px;padding-right:0px;padding-bottom:20px;padding-left:0px;font-size:26px;line-height:36px;}.wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_0a820c-26[data-kb-block=\"kb-adv-heading968_0a820c-26\"] mark.kt-highlight{border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}}<\/style>\n<h3 class=\"kt-adv-heading968_0a820c-26 underline wp-block-kadence-advancedheading hls-none\" data-kb-block=\"kb-adv-heading968_0a820c-26\">Ketahuilah yang kucing-kucing anda akan baik-baik sahaja di bawah jagaan kami.<\/h3>\n<\/div><\/div>\n\n\n<style>.kadence-column968_d772c2-ff > .kt-inside-inner-col,.kadence-column968_d772c2-ff > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_d772c2-ff > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_d772c2-ff > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_d772c2-ff > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_d772c2-ff > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_d772c2-ff{position:relative;}@media all and (max-width: 1024px){.kadence-column968_d772c2-ff{text-align:center;}}@media all and (max-width: 1024px){.kadence-column968_d772c2-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_d772c2-ff{text-align:center;}.kadence-column968_d772c2-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_d772c2-ff kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.kb-image968_14b583-fa .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_14b583-fa img.kb-img, .kb-image968_14b583-fa .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_14b583-fa kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port23\"><img decoding=\"async\" width=\"1080\" height=\"810\" src=\"https:\/\/nekosuites.com\/wp-content\/uploads\/Sun-with-fatboy-2.jpg\" alt=\"\" class=\"kb-img wp-image-827\" title=\"\" srcset=\"https:\/\/nekosuites.com\/wp-content\/uploads\/Sun-with-fatboy-2.jpg 1080w, https:\/\/nekosuites.com\/wp-content\/uploads\/Sun-with-fatboy-2-300x225.jpg 300w, https:\/\/nekosuites.com\/wp-content\/uploads\/Sun-with-fatboy-2-1024x768.jpg 1024w, https:\/\/nekosuites.com\/wp-content\/uploads\/Sun-with-fatboy-2-768x576.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column968_ed8d61-5e > .kt-inside-inner-col,.kadence-column968_ed8d61-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_ed8d61-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_ed8d61-5e > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_ed8d61-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_ed8d61-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_ed8d61-5e{position:relative;}@media all and (max-width: 1024px){.kadence-column968_ed8d61-5e{text-align:center;}}@media all and (max-width: 1024px){.kadence-column968_ed8d61-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_ed8d61-5e{text-align:center;}.kadence-column968_ed8d61-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_ed8d61-5e inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kb-image968_c1a5c1-f3 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kb-image968_c1a5c1-f3 img.kb-img, .kb-image968_c1a5c1-f3 .kb-img img{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image968_c1a5c1-f3 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port23\"><img decoding=\"async\" width=\"1080\" height=\"1323\" src=\"https:\/\/nekosuites.com\/wp-content\/uploads\/Janice-and-orange-1.jpg\" alt=\"\" class=\"kb-img wp-image-818\" title=\"\" srcset=\"https:\/\/nekosuites.com\/wp-content\/uploads\/Janice-and-orange-1.jpg 1080w, https:\/\/nekosuites.com\/wp-content\/uploads\/Janice-and-orange-1-245x300.jpg 245w, https:\/\/nekosuites.com\/wp-content\/uploads\/Janice-and-orange-1-836x1024.jpg 836w, https:\/\/nekosuites.com\/wp-content\/uploads\/Janice-and-orange-1-768x941.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id968_5b1e4a-2f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id968_5b1e4a-2f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id968_5b1e4a-2f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1475px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-right:25px;padding-bottom:40px;padding-left:25px;min-height:572px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id968_5b1e4a-2f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id968_5b1e4a-2f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id968_5b1e4a-2f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id968_5b1e4a-2f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column968_470792-98 > .kt-inside-inner-col{display:flex;}.kadence-column968_470792-98 > .kt-inside-inner-col,.kadence-column968_470792-98 > .kt-inside-inner-col:before{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kadence-column968_470792-98 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_470792-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_470792-98 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column968_470792-98{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_470792-98{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_470792-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_470792-98 > .kt-inside-inner-col{background-image:url('http:\/\/nekosuites.com\/wp-content\/uploads\/Fatboy-on-shelf-in-Superior-Suite.jpg');background-size:cover;background-position:28.999999999999996% 1%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column968_470792-98 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_470792-98{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column968_470792-98{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_470792-98{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_470792-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column968_470792-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column968_470792-98{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_470792-98{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_470792-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_470792-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column968_470792-98 { min-height: 300px!important; }<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_470792-98 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-968_cc1b39-c2 .kt-block-spacer{height:300px;}.wp-block-kadence-spacer.kt-block-spacer-968_cc1b39-c2 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-968_cc1b39-c2 kvs-lg-false\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column968_c85b2b-7b > .kt-inside-inner-col{display:flex;}.kadence-column968_c85b2b-7b > .kt-inside-inner-col{padding-right:60px;padding-left:60px;}.kadence-column968_c85b2b-7b > .kt-inside-inner-col,.kadence-column968_c85b2b-7b > .kt-inside-inner-col:before{border-top-left-radius:24px;border-top-right-radius:24px;border-bottom-right-radius:24px;border-bottom-left-radius:24px;}.kadence-column968_c85b2b-7b > .kt-inside-inner-col{column-gap:10px;}.kadence-column968_c85b2b-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_c85b2b-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column968_c85b2b-7b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_c85b2b-7b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_c85b2b-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_c85b2b-7b > .kt-inside-inner-col{background-color:var(--global-palette7, #EDF2F7);}.kadence-column968_c85b2b-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_c85b2b-7b{text-align:center;}.kadence-column968_c85b2b-7b{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column968_c85b2b-7b{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_c85b2b-7b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_c85b2b-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column968_c85b2b-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_c85b2b-7b > .kt-inside-inner-col{padding-top:20px;padding-right:25px;padding-bottom:20px;padding-left:25px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column968_c85b2b-7b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_c85b2b-7b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column968_c85b2b-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column968_c85b2b-7b, .kt-inside-inner-col > .kadence-column968_c85b2b-7b:not(.specificity){margin-bottom:25px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_c85b2b-7b kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0, .wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"]{text-align:center;font-size:56px;line-height:70px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"] a, .kt-adv-heading-link968_06537c-c0, .kt-adv-heading-link968_06537c-c0 .kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"]{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"] a, a.kb-advanced-heading-link.kt-adv-heading-link968_06537c-c0{text-decoration:none;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0, .wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"]{padding-right:20px;padding-left:20px;font-size:42px;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"] mark.kt-highlight{border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0, .wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"]{padding-top:20px;padding-right:0px;padding-bottom:20px;padding-left:0px;font-size:26px;line-height:36px;}.wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_06537c-c0[data-kb-block=\"kb-adv-heading968_06537c-c0\"] mark.kt-highlight{border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}}<\/style>\n<h3 class=\"kt-adv-heading968_06537c-c0 underline wp-block-kadence-advancedheading hls-none\" data-kb-block=\"kb-adv-heading968_06537c-c0\">Jadikan Neko Suites rumah kedua buat kucing-kucing anda.<\/h3>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id968_f0c22d-02 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id968_f0c22d-02 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id968_f0c22d-02 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:900px;margin-left:auto;margin-right:auto;padding-top:41px;padding-right:25px;padding-bottom:40px;padding-left:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id968_f0c22d-02 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id968_f0c22d-02 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id968_f0c22d-02 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id968_f0c22d-02 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column968_124656-c0 > .kt-inside-inner-col,.kadence-column968_124656-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column968_124656-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column968_124656-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column968_124656-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column968_124656-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column968_124656-c0{text-align:center;}.kadence-column968_124656-c0{position:relative;}@media all and (max-width: 1024px){.kadence-column968_124656-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column968_124656-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column968_124656-c0 { }<\/style>\n<div class=\"wp-block-kadence-column kadence-column968_124656-c0 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading968_6c60c6-3c, .wp-block-kadence-advancedheading.kt-adv-heading968_6c60c6-3c[data-kb-block=\"kb-adv-heading968_6c60c6-3c\"]{text-align:center;font-size:20px;font-weight:400;font-style:normal;font-family:'Work Sans';}.wp-block-kadence-advancedheading.kt-adv-heading968_6c60c6-3c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_6c60c6-3c[data-kb-block=\"kb-adv-heading968_6c60c6-3c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_6c60c6-3c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_6c60c6-3c[data-kb-block=\"kb-adv-heading968_6c60c6-3c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading968_6c60c6-3c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading968_6c60c6-3c\">Testimoni<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading968_c98c62-74, .wp-block-kadence-advancedheading.kt-adv-heading968_c98c62-74[data-kb-block=\"kb-adv-heading968_c98c62-74\"]{font-size:36px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading968_c98c62-74 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading968_c98c62-74[data-kb-block=\"kb-adv-heading968_c98c62-74\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading968_c98c62-74 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading968_c98c62-74[data-kb-block=\"kb-adv-heading968_c98c62-74\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading968_c98c62-74 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading968_c98c62-74\">Maklum Balas Daripada Pelanggan<\/p>\n\n\n<pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-disable-font ti-show-rating-text ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"%d %s ago|today|day|days|week|weeks|month|months|year|years\" data-plugin-version=\"13.3.1\" data-layout-id=\"33\" data-layout-category=\"list\" data-set-id=\"soft\" data-pid=\"\" data-language=\"en\" data-close-locale=\"Close\" data-css-version=\"2\" data-reply-by-locale=\"Owner&apos;s reply\" data-only-rating-locale=\"This user only left a rating.\" data-load-more-rows=\"5\"> <div class=\"ti-widget-container\"> <div class=\"ti-header source-Google\"> <div class=\"ti-mob-row\"> <span class=\"nowrap\"><strong>EXCELLENT<\/strong><\/span> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <\/div> <div class=\"ti-mob-row\"> <span class=\"nowrap\"><strong>41 reviews<\/strong><\/span><div class=\"ti-small-logo\"><trustindex-image data-imgurl=\"https:\/\/nekosuites.com\/wp-content\/plugins\/wp-reviews-plugin-for-google\/static\/img\/platform\/logo.svg?ver=do-not-care-13.3.1\" alt=\"Google\" width=\"150\" height=\"25\" loading=\"lazy\"><\/trustindex-image><\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1763164800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLAKpzl-ZZGYV9jF4LsrYW4OCq8muKnVs0WNh83HZcXw_iKmA=w40-h40-c-rp-mo-br100\" alt=\"mazlina azhar profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> mazlina azhar <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->I found Neko Suites by chance, and I loved it. It's clean, spacious and quiet, just ideal for my fur baby, Harry. The first time Harry came here last September, she was aloof, unfriendly and never stepped out of her room. A week ago I sent her again, this time however Harry felt really at home. She ventured out of her room freely, basking and relaxing in the morning sun and interacting comfortably with both the owners. I was miles away yet I had the peace of mind knowing Harry was well taken care of and attended to all the time. So kudos to Neko Suites Cat Hotel, keep it up!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1762819200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVeH_cZ7L7htDmS814C0dUuxjTEqC52GrjlEIs7K6Bd5ay_hQJkCg=w40-h40-c-rp-mo-br100\" alt=\"Noor Azizi Bin Mohd Din Azizi profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Noor Azizi Bin Mohd Din Azizi <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->Excellent place to leave your beloved cats. Sent my two cats there for five days and was taken care extremely well. Given enough playtimes every day. Updated every day too. Will send them there again if the need arises.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1756512000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV_YAgdgDdt1VwzdCheAhnVLPTj3TsALz7LIim8xPVOPRJWAptY=w40-h40-c-rp-mo-ba3-br100\" alt=\"Xian Bing Chew profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Xian Bing Chew <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->The place is SIMPLY AMAZING. The place was clean, like super super clean. Even the accomodations are so comfy and nice. My cat had been to other boardings too, and he never liked any of them at all. Often he'll just coop up in a corner. Many of the boardings I've went don't even have place for cats to just play around. But here, 'chun', He loves the place a lot. And the staffs are always taking time playing with the cats. It's superb. The price is also cheap, very cheap as far as I know. Thanks to them, I can simply have my cat here if I ever need to travel.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1755043200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUpJYqwtta8BfRRPF_nRVaG8JxacNnEpgitsZpEovnLW61KM0K-=w40-h40-c-rp-mo-ba3-br100\" alt=\"najihah hassan profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> najihah hassan <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->saya sangat2 berpuas hati letak si bulus di hotel ni\u2764\ufe0f setiap hari update dengan detail, kucing tak stress dan layanan sangat terbaik\ud83d\udc4d\ud83c\udffb sesiapa nak pergi travel sila lah hantar anak2 bulus di sini. Harga pon sangat2 okey.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1752278400\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVDT0gVqd_uVCPVww6_wT9jgjTiXn38tlyJl_FujDJ_hEGy-_yivQ=w40-h40-c-rp-mo-br100\" alt=\"Mika Enr\u00edquez Brzezinski profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Mika Enr\u00edquez Brzezinski <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->We had just moved to Perak and needed to go for outstation for business purposes, so we entrusted Neko suites to care for our cats.\n\nDodi had stayed at many Cats Boarding Hotel across Johor, Melaka, KL\/Selangor and now at Perak, even the ones we have booked through PetBacker apps.\n\nMeanwhile, this is Abu's second stay at a boarding hotel.\n\nI can say the carers make both of our cats comfortable despite their different personalities, one is friendlier, one is a bit shy.\n\nI seem to notice that this is one of the least carer that interacts in play sessions with my cats and I only know this because they update us too frequent which is also good.\n\nMind you, our cats are a combination of obese and the other one slightly malnourished.\n\nFacilities are good, playroom is huge, cats have individual \"house\" instead of the conventional side-by-side cages in pet boarding hotels.\n\nPricing wise, is quite competitive and is on par with the care they provide for our pets.\n\nHoping they will provide grooming services in the near future.\n\nThank you for caring for our babies.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1747699200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJNlYjZvNa5dEH5swqyf5V5PMEP7EDyGIS-Zc5CWy0p0wGhtw=w40-h40-c-rp-mo-br100\" alt=\"Lee Pei xin profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Lee Pei xin <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->\u7b2c\u4e00\u6b21\u628a\u6211\u5bb6\u732b\u653e\u5728\u8fd9\u91cc\uff0c\u73af\u5883\u975e\u5e38\u5e72\u51c0\u4e00\u70b9\u5f02\u5473\u90fd\u6ca1\u6709\uff0c\u8d1f\u8d23\u4eba\u5f88\u7ec6\u5fc3\u7167\u987e\uff0c\u8fd8\u4f1a\u966a\u732b\u54aa\u73a9\ud83e\udd23\u4e00\u5929\u4f1a\u53d1\u597d\u51e0\u6b21\u7167\u7247\u548c\u5f71\u7247\u8ba9\u6211\u4eec\u770b\u81ea\u5df1\u7684\u732b\u732b\uff0c\u975e\u5e38\u63a8\u8350\uff01<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1747008000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ3omoDi7pMB2KJyB49mDH1cfYYJ_b9rz7jKOGTcu6wq5azFw=w40-h40-c-rp-mo-br100\" alt=\"NIVARTHINI A\/P MANIKAM profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> NIVARTHINI A\/P MANIKAM <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->Really appreciate the continuous update from Janice and Sung, the best cat hotel ever.. their hospitality and care given to my cat wonderful. Thank you to both of you..<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1744070400\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUc6J8Tk3KhhsllkyHSRv4cV-fiYvfAn14jg4sO1lW78yHg0SBx=w40-h40-c-rp-mo-br100\" alt=\"Nurul Sakinah profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Nurul Sakinah <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->Haritu I hantar kucing2 I dekat sini masa raya. Lucky me still ada tempat even I booked last minute. Love everything about the place! The environment is also very clean and I suka sebab takde banyak kucing sangat. The owners also very friendly and always keeps me updated with pictures and videos of my cats (lepas rindu masa balik kampung haritu\ud83e\udd23). Also since this is my cats first time hantar dekat tempat boarding, I was a bit worried at first. But lucky me the owners took such a good care of them and try to play with them until they become comfortable there. Overall highly recommend to other cat owners to send their cats here\ud83d\udc4d\ud83c\udffb<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1743465600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjW3451pBoTBkkKHuDzfSz5MG-rsedfJGd5DfQBmiRceayPrs8fH=w40-h40-c-rp-mo-ba3-br100\" alt=\"Nur Nadhira profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Nur Nadhira <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->I recently boarded my cats here, and I must say their service is exceptional compared to other boarding places. They kept me updated regularly, which I truly appreciate. My cats are usually hard to please, but somehow they managed to create a comfortable and less stressful environment for them. You can really tell they are genuine cat lovers. Highly recommended!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1741305600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Posted on Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXnqIcjrjnsH05oJ9Q2IAqRx8eC94oepdgw29uykkSyGtsGt6MV=w40-h40-c-rp-mo-ba3-br100\" alt=\"Suzanne Lee profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Suzanne Lee <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-review-content\"> <div class=\"ti-review-text-container ti-inner\"><!-- R-CONTENT -->Very good and clean environment for cats. The person in charge is very responsive and takes great care of the cats. My cat looked happy and enjoyed its stay there. I have experienced several boarding places, and I would say this is the best one. Highly recommended for those looking for a cat hotel.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content .ti-inner\" data-collapse-text=\"Hide\" data-open-text=\"Read more\"><\/span> <\/div> <\/div> <\/div>  <\/div>  <\/div>   <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/nekosuites.com\/wp-content\/uploads\/trustindex-google-widget.css?1782548853\"><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns968_9dca72-97{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns968_9dca72-97 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns968_9dca72-97\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);font-size:nonepx;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);padding-right:55px;padding-left:55px;}.wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button:focus{color:var(--global-palette2, #2B6CB0);background:var(--global-palette1, #3182CE);border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button{border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button{border-top:1px solid var(--global-palette5, #4A5568);border-right:1px solid var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette5, #4A5568);border-left:1px solid var(--global-palette5, #4A5568);}.wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn968_2b9606-00.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn968_2b9606-00 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/goo.gl\/maps\/4jPwzUwVLG5E9UQc6\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">More Reviews<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Hotel Kucing Neko Suites &#8211; Penginapan Kucing Di Ipoh Tempah penginapan percutian buat kucing anda. Kami ingin membuatkan kucing anda berasa seperti di rumah sendiri di hotel kucing kami di Ipoh. Kemudahan Di Hotel Kucing Neko Suites, Ipoh Misi Kami Ingin pergi ke mana-mana tetapi tidak boleh bawa kucing kesayangan? Kami faham perasaan anda. Ketahuilah&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"enable","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-968","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nekosuites.com\/ms\/wp-json\/wp\/v2\/pages\/968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nekosuites.com\/ms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nekosuites.com\/ms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nekosuites.com\/ms\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nekosuites.com\/ms\/wp-json\/wp\/v2\/comments?post=968"}],"version-history":[{"count":0,"href":"https:\/\/nekosuites.com\/ms\/wp-json\/wp\/v2\/pages\/968\/revisions"}],"wp:attachment":[{"href":"https:\/\/nekosuites.com\/ms\/wp-json\/wp\/v2\/media?parent=968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}